{"id":3298,"date":"2020-08-17T08:51:46","date_gmt":"2020-08-17T11:51:46","guid":{"rendered":"http:\/\/www.fpnadvogados.com.br\/site\/?p=3298"},"modified":"2020-08-21T07:56:43","modified_gmt":"2020-08-21T10:56:43","slug":"planejamento-tributario-e-fundamental-para-reduzir-perdas-nos-negocios-na-pandemia","status":"publish","type":"post","link":"https:\/\/www.fpnadvogados.com.br\/site\/planejamento-tributario-e-fundamental-para-reduzir-perdas-nos-negocios-na-pandemia\/","title":{"rendered":"Planejamento tribut\u00e1rio \u00e9 fundamental para reduzir perdas nos neg\u00f3cios na pandemia"},"content":{"rendered":"<figure id=\"attachment_3251\" aria-describedby=\"caption-attachment-3251\" style=\"width: 200px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-3251\" src=\"http:\/\/www.fpnadvogados.com.br\/site\/wp-content\/uploads\/2016\/03\/Eduarda-04-200x300.jpg\" alt=\"Eduarda Prada Radtke, advogada tributarista\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.fpnadvogados.com.br\/site\/wp-content\/uploads\/2016\/03\/Eduarda-04-200x300.jpg 200w, https:\/\/www.fpnadvogados.com.br\/site\/wp-content\/uploads\/2016\/03\/Eduarda-04-768x1152.jpg 768w, https:\/\/www.fpnadvogados.com.br\/site\/wp-content\/uploads\/2016\/03\/Eduarda-04-683x1024.jpg 683w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-3251\" class=\"wp-caption-text\">Eduarda Prada Radtke, advogada tributarista<\/figcaption><\/figure>\n<p><i>Eduarda Prada Radtke, da\u00a0<span class=\"il\">Fl\u00e1vio<\/span>\u00a0<span class=\"il\">Pinheiro<\/span>\u00a0<span class=\"il\">Neto<\/span>\u00a0Advogados, destaca que empresas precisam avaliar a posterga\u00e7\u00e3o de prazos bem como estar atentas a redu\u00e7\u00e3o de impostos e evitar o ac\u00famulo de tributos nos pr\u00f3ximos meses<\/i><\/p>\n<div>\n<div>\n<p>Com os efeitos da pandemia impactando os neg\u00f3cios, \u00e9 cada vez maior a busca por novos prazos e redu\u00e7\u00e3o de custos nas empresas. N\u00e3o \u00e9 diferente quando se fala em gest\u00e3o tribut\u00e1ria, especialmente com a publica\u00e7\u00e3o de medidas provis\u00f3rias que visam dar \u00e0s empresas mais prazos para o cumprimento de obriga\u00e7\u00f5es tribut\u00e1rias.<\/p>\n<p>Para Eduarda Prada Radtke, advogada do setor tribut\u00e1rio da\u00a0<span class=\"il\">Fl\u00e1vio<\/span>\u00a0<span class=\"il\">Pinheiro<\/span>\u00a0<span class=\"il\">Neto<\/span>\u00a0Advogados, a tomada de decis\u00e3o assertiva neste momento \u00e9 fundamental para a redu\u00e7\u00e3o de perdas nas empresas. \u201cNo entanto, \u00e9 preciso se criar um planejamento eficiente na gest\u00e3o de tributos, a fim de evitar problemas em longo prazo. Muitos prazos foram estendidos e posterg\u00e1-los pode ser uma op\u00e7\u00e3o de fortalecimento de caixa neste momento desafiador. Por\u00e9m, a assessoria jur\u00eddica neste momento ser\u00e1 primordial para n\u00e3o s\u00f3 adiar, mas tamb\u00e9m renegociar pagamentos, cortar excessos e atuar com mais efici\u00eancia fiscal, levando em considera\u00e7\u00e3o os efeitos em m\u00e9dio e longo prazo\u201d, comenta.<\/p>\n<p>Dentro do planejamento tribut\u00e1rio, a advogada destaca que h\u00e1 algumas a\u00e7\u00f5es que devem ser verificadas, que v\u00e3o desde a revis\u00e3o do pagamento de tributos at\u00e9 o tipo de desconto que pode ser concedido. \u201cAl\u00e9m disso, o apoio de especialistas vai ajudar as empresas a entenderem o momento atual e os impactos futuros ao neg\u00f3cio. H\u00e1, por exemplo, a possibilidade do resgate de tributos, o que \u00e9 fundamental em um momento de recess\u00e3o econ\u00f4mica. Tamb\u00e9m \u00e9 necess\u00e1rio ter um planejamento para a retomada da economia e de que forma a efici\u00eancia fiscal ser\u00e1 garantida tamb\u00e9m nesta situa\u00e7\u00e3o\u201d, diz.<\/p>\n<p>No Brasil, a tributa\u00e7\u00e3o ocorre dentro de algumas op\u00e7\u00f5es de regime, como Lucro Real, Lucro Presumido, Lucro Arbitrado e Simples Nacional. Existem regras e percentuais espec\u00edfico sobre cada um deles e para se adequar a determinado modelo a empresa deve preencher requisitos espec\u00edficos. \u201cNeste momento, at\u00e9 mesmo a mudan\u00e7a no regime de tributa\u00e7\u00e3o pode ser avaliada e o ideal \u00e9 que se busque atrav\u00e9s da assessoria e da concilia\u00e7\u00e3o a resolu\u00e7\u00e3o dos pagamentos, evitando medidas judiciais que podem levar ao desgaste. Um bom planejamento leva tudo isso em considera\u00e7\u00e3o\u201d, finaliza Eduarda.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eduarda Prada Radtke, da\u00a0Fl\u00e1vio\u00a0Pinheiro\u00a0Neto\u00a0Advogados, destaca que empresas precisam avaliar a posterga\u00e7\u00e3o de prazos bem como estar atentas a redu\u00e7\u00e3o de impostos e evitar o ac\u00famulo de tributos nos pr\u00f3ximos meses Com os efeitos da pandemia impactando os neg\u00f3cios, \u00e9 cada vez maior a busca por novos prazos e redu\u00e7\u00e3o de custos nas empresas. N\u00e3o \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[38,40,44,46,47,39,45,36,37,49,50,41,48,43,42],"class_list":["post-3298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-especialidades","tag-advocacia-em-blumenau","tag-blumenau","tag-direito-digital","tag-direito-digital-blumenau","tag-direto-para-startups","tag-escritorio-de-advocacia","tag-especialista-em-direito-digital","tag-flavio-pinheiro-neto","tag-flavio-pinheiro-neto-advogados-associados","tag-gestao-tributaria","tag-planejamento-tributario","tag-santa-catarina","tag-startups","tag-vale-do-itajai","tag-vale-europeu"],"_links":{"self":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/comments?post=3298"}],"version-history":[{"count":2,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3298\/revisions"}],"predecessor-version":[{"id":3302,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3298\/revisions\/3302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media\/3303"}],"wp:attachment":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media?parent=3298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/categories?post=3298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/tags?post=3298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}