{"id":3319,"date":"2020-09-15T11:44:48","date_gmt":"2020-09-15T14:44:48","guid":{"rendered":"http:\/\/www.fpnadvogados.com.br\/site\/?p=3319"},"modified":"2020-09-15T11:44:48","modified_gmt":"2020-09-15T14:44:48","slug":"edital-receita-federal","status":"publish","type":"post","link":"https:\/\/www.fpnadvogados.com.br\/site\/edital-receita-federal\/","title":{"rendered":"Edital da Receita Federal traz descontos de at\u00e9 50% no parcelamento de d\u00edvidas de micro e pequenas empresas"},"content":{"rendered":"<p><i>A advogada tributarista\u00a0<span class=\"il\">Eduarda<\/span>\u00a0<span class=\"il\">Prada<\/span>\u00a0Radtke, da Fl\u00e1vio Pinheiro Neto Advogados, explica quem pode aderir ao benef\u00edcio e as regras contidas na publica\u00e7\u00e3o n\u00ba 1\/2020 do \u00f3rg\u00e3o<\/i><\/p>\n<div>\n<p>Um novo edital da Receita Federal, publicado na \u00faltima semana, deve facilitar o pagamento de tributos atrasados que pequenos neg\u00f3cios tenham com a entidade, com descontos de at\u00e9 50% dos d\u00e9bitos. O edital n\u00ba 1\/2020 tem o objetivo de resolver processos administrativos que, segundo o \u00f3rg\u00e3o s\u00e3o mais de 340 mil em aberto.<\/p>\n<p>A advogada tributarista\u00a0<span class=\"il\">Eduarda<\/span>\u00a0<span class=\"il\">Prada<\/span>\u00a0Radkte, da Fl\u00e1vio Pinheiro Neto Advogados, explica quais empresas ser\u00e3o beneficiadas com as condi\u00e7\u00f5es facilitadas de pagamento. \u201cPodem aderir ao edital microempresas e empresas de pequeno porte que desistirem dos recursos administrativos relacionados \u00e0 negocia\u00e7\u00e3o de tributos vencidos, declarando-se devedoras destes d\u00e9bitos. A d\u00edvida n\u00e3o pode ser superior a 60 sal\u00e1rios m\u00ednimos na data de ades\u00e3o, incluindo nesta soma multa de of\u00edcio que tenha vencimento at\u00e9 31 de dezembro de 2019\u201d, diz.<\/p>\n<p>A jurista destaca que a ades\u00e3o carece de aprova\u00e7\u00e3o do \u00f3rg\u00e3o e quem tiver interesse em se candidatar ao edital deve realizar a inscri\u00e7\u00e3o atrav\u00e9s do site da Receita Federal, entre 16 de setembro e 29 de dezembro. \u201cAo ser aceito no edital, o contribuinte deve dar uma entrada de 6% da d\u00edvida que restar depois da aplica\u00e7\u00e3o dos descontos, que podem chegar a at\u00e9 50% do valor total. Esse desconto m\u00e1ximo ser\u00e1 concedido a quem parcelar a entrada em at\u00e9 cinco meses e o restante do d\u00e9bito em at\u00e9 sete meses. Quanto menor a quantidade de parcelas, maior o desconto\u201d, comenta.<\/p>\n<p>Atualmente, a Receita Federal estima que a d\u00edvida de d\u00e9bitos em impostos que est\u00e3o sendo discutidos atrav\u00e9s de processos administrativos some R$ 10,7 bilh\u00f5es.<\/p>\n<p><span class=\"il\">Eduarda<\/span>\u00a0lista as demais regras para quem decidir quitar seus d\u00e9bitos com a Receita atrav\u00e9s do edital n\u00ba 1\/2020:<\/p>\n<p>&#8211; Quem parcelar a entrada da d\u00edvida em at\u00e9 seis meses e o restante em at\u00e9 18 meses ter\u00e1 abatimento de 40% do valor total;<\/p>\n<p>&#8211; Parcelamentos de entrada em at\u00e9 sete vezes e o restante em 29 meses proporcionam desconto de 30% da d\u00edvida;<\/p>\n<p>&#8211; J\u00e1 quem parcelar a entrada em oito meses e o restante da d\u00edvida em 52 meses ser\u00e1 beneficiado com 20% de desconto.<\/p>\n<p>Para\u00a0<span class=\"il\">Eduarda<\/span>, o edital \u00e9 uma boa oportunidade para quem busca regularizar sua situa\u00e7\u00e3o com o Fisco. \u201cOs descontos s\u00e3o bem interessantes e, se forem colocados dentro de um contexto de planejamento tribut\u00e1rio eficiente \u00e9 uma sa\u00edda para as empresas otimizarem seu caixa e garantirem liquida\u00e7\u00e3o de d\u00e9bitos para, inclusive, a busca por cr\u00e9ditos no mercado financeiro\u201d, avalia.<\/p>\n<p>O edital e o requerimento para ades\u00e3o podem ser acessados no portal do Centro Virtual de Atendimento, no site da Receita Federal, no servi\u00e7o \u201cTransa\u00e7\u00e3o\u201d.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A advogada tributarista\u00a0Eduarda\u00a0Prada\u00a0Radtke, da Fl\u00e1vio Pinheiro Neto Advogados, explica quem pode aderir ao benef\u00edcio e as regras contidas na publica\u00e7\u00e3o n\u00ba 1\/2020 do \u00f3rg\u00e3o Um novo edital da Receita Federal, publicado na \u00faltima semana, deve facilitar o pagamento de tributos atrasados que pequenos neg\u00f3cios tenham com a entidade, com descontos de at\u00e9 50% dos d\u00e9bitos. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[38,40,44,46,47,39,45,36,37,49,50,41,48,43,42],"class_list":["post-3319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-especialidades","tag-advocacia-em-blumenau","tag-blumenau","tag-direito-digital","tag-direito-digital-blumenau","tag-direto-para-startups","tag-escritorio-de-advocacia","tag-especialista-em-direito-digital","tag-flavio-pinheiro-neto","tag-flavio-pinheiro-neto-advogados-associados","tag-gestao-tributaria","tag-planejamento-tributario","tag-santa-catarina","tag-startups","tag-vale-do-itajai","tag-vale-europeu"],"_links":{"self":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/comments?post=3319"}],"version-history":[{"count":1,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3319\/revisions"}],"predecessor-version":[{"id":3321,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3319\/revisions\/3321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media\/3320"}],"wp:attachment":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media?parent=3319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/categories?post=3319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/tags?post=3319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}