{"id":3459,"date":"2021-12-03T15:13:38","date_gmt":"2021-12-03T18:13:38","guid":{"rendered":"https:\/\/www.fpnadvogados.com.br\/site\/?p=3459"},"modified":"2021-11-19T15:23:50","modified_gmt":"2021-11-19T18:23:50","slug":"planejamento%e2%80%8c-%e2%80%8c%e2%80%8ctributario%e2%80%8c-%e2%80%8ce%e2%80%8c-%e2%80%8caliado%e2%80%8c-%e2%80%8cde%e2%80%8c-%e2%80%8cempresas%e2%80%8c-%e2%80%8cdurante%e2%80%8c-%e2%80%8cretomada","status":"publish","type":"post","link":"https:\/\/www.fpnadvogados.com.br\/site\/planejamento%e2%80%8c-%e2%80%8c%e2%80%8ctributario%e2%80%8c-%e2%80%8ce%e2%80%8c-%e2%80%8caliado%e2%80%8c-%e2%80%8cde%e2%80%8c-%e2%80%8cempresas%e2%80%8c-%e2%80%8cdurante%e2%80%8c-%e2%80%8cretomada\/","title":{"rendered":"Planejamento\u200c \u200c\u200ctribut\u00e1rio\u200c \u200c\u00e9\u200c \u200caliado\u200c \u200cde\u200c \u200cempresas\u200c \u200cdurante\u200c \u200cretomada\u200c \u200cecon\u00f4mica\u200c \u200c"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Se h\u00e1 uma coisa que a pandemia ensinou ao empresariado \u00e9 a import\u00e2ncia do planejamento. Pr\u00f3ximo a encerrar o ano, a advogada tributarista, Eduarda Prada Radtke, explica que o alinhamento de um planejamento tribut\u00e1rio permite que empresas garantam uma atua\u00e7\u00e3o s\u00f3lida e saud\u00e1vel para o pr\u00f3ximo ano. \u201cOs tributos brasileiros s\u00e3o alt\u00edssimos, por isso \u00e9 importante que empresas realizem uma an\u00e1lise e definam o melhor regime a ser adotado. Por meio de um planejamento estruturado \u00e9 poss\u00edvel buscar a forma mais eficiente e legal de atua\u00e7\u00e3o para assegurar a sa\u00fade financeira da organiza\u00e7\u00e3o\u201d, cita a especialista do escrit\u00f3rio Fl\u00e1vio Pinheiro Neto Advogados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acordo com a pesquisa Desafios dos Empreendedores Brasileiros, realizada pela Endeavor, 22% dos gestores entrevistados encontram dificuldades na realiza\u00e7\u00e3o do planejamento. Segundo a advogada, isso ocorre devido \u00e0 falta de conhecimento das etapas que comp\u00f5em o processo. \u201cO planejamento n\u00e3o \u00e9 uma atividade simples. O primeiro passo \u00e9 conhecer profundamente a atividade da empresa, os objetivos que se pretende alcan\u00e7ar, mapeando atividades e coletando informa\u00e7\u00f5es sobre faturamento, despesas, operacionaliza\u00e7\u00e3o, lucratividade, etc. S\u00e3o estes indicadores que d\u00e3o base para adequar as solu\u00e7\u00f5es tribut\u00e1rias encontradas pelo profissional em conformidade com as legisla\u00e7\u00f5es vigentes\u201d, cita.<\/span><\/p>\n<p><b>Simples, Lucro Real ou Lucro Presumido?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A an\u00e1lise dos indicadores de performance permite estruturar estrat\u00e9gias convenientes para empresas no que diz respeito ao enquadramento tribut\u00e1rio a ser escolhido para o ano. Com diversos fatores influenciando no enquadramento e ades\u00e3o do regime tribut\u00e1rio das empresas, a advogada esclarece que os regimes tribut\u00e1rios podem ser<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><b>Simples Nacional:<\/b><span style=\"font-weight: 400;\"> Ideal para empresas de micro e pequeno porte, onde o recolhimento de impostos \u00e9 simplificado, oferecendo al\u00edquotas reduzidas para os empreendedores. Para micro empresas o faturamento deve chegar at\u00e9 R$ 360 mil, enquanto para Empresas de Pequeno Porte o limite \u00e9 de at\u00e9 R$ 4,8 milh\u00f5es.<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Lucro Presumido: <\/b><span style=\"font-weight: 400;\">empresas de todos os portes podem aderir a este enquadramento, por\u00e9m o faturamento anual n\u00e3o pode ultrapassar o valor de R$ 78 milh\u00f5es. Nesta modalidade o recolhimento do tributo acontece com base nos lucros durante um per\u00edodo determinado.<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Lucro Real: <\/b><span style=\"font-weight: 400;\">a base para este regime \u00e9 o lucro cont\u00e1bil das organiza\u00e7\u00f5es que atingem o faturamento anual superior a R$ 78 milh\u00f5es.<\/span><\/li>\n<\/ul>\n<p><b>Distribui\u00e7\u00e3o de lucros: voc\u00ea paga imposto sobre ele<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Eduarda tamb\u00e9m cita algumas provid\u00eancias importantes a serem adotadas pela empresa na busca de uma boa sa\u00fade financeira, como a distribui\u00e7\u00e3o de lucros e dividendos. \u201cA remunera\u00e7\u00e3o do s\u00f3cio ou acionista n\u00e3o possui al\u00edquota de Imposto de Renda de Pessoa F\u00edsica (IRPF) e nem Contribui\u00e7\u00e3o Previdenci\u00e1ria (INSS). Diferente do pr\u00f3-labore, a atividade, que \u00e9 um instrumento legal, permite que o empreendedor seja compensado pelo seu empreendimento e o risco assumido na abertura do neg\u00f3cio\u201d, enfatiza Radtke, que destaca a possibilidade de mudan\u00e7a nesta condi\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A segunda fase da reforma tribut\u00e1ria, que traz o <\/span><span style=\"font-weight: 400;\">PL 2337\/2021, j\u00e1 aprovado na C\u00e2mara dos <\/span><span style=\"font-weight: 400;\">Deputados <\/span><span style=\"font-weight: 400;\">e que tramita agora no Senado, prev\u00ea uma tributa\u00e7\u00e3o de 15% sobre a distribui\u00e7\u00e3o de lucros e dividendos. \u201cSe aprovada, a mudan\u00e7a precisa ser levada em considera\u00e7\u00e3o na gest\u00e3o tribut\u00e1ria das empresas, pois afetar\u00e1 diretamente uma pr\u00e1tica comum nos neg\u00f3cios. Neste caso, uma revis\u00e3o do planejamento tribut\u00e1rio \u00e9 ainda mais importante para manter a sa\u00fade financeira do neg\u00f3cio\u201d, finaliza a jurista.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se h\u00e1 uma coisa que a pandemia ensinou ao empresariado \u00e9 a import\u00e2ncia do planejamento. Pr\u00f3ximo a encerrar o ano, a advogada tributarista, Eduarda Prada Radtke, explica que o alinhamento de um planejamento tribut\u00e1rio permite que empresas garantam uma atua\u00e7\u00e3o s\u00f3lida e saud\u00e1vel para o pr\u00f3ximo ano. \u201cOs tributos brasileiros s\u00e3o alt\u00edssimos, por isso \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[80,38,58,52,60,53,85,39,36,37,49,83,84,67,65,79,50,82,81],"class_list":["post-3459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-80","tag-advocacia-em-blumenau","tag-amparo-juridico","tag-assessoria-juridica","tag-cultura-organizacional","tag-direito-empresarial","tag-distribuicao-de-lucros","tag-escritorio-de-advocacia","tag-flavio-pinheiro-neto","tag-flavio-pinheiro-neto-advogados-associados","tag-gestao-tributaria","tag-lucro-presumido","tag-lucro-real","tag-mitigacao-de-riscos","tag-modelos-de-negocio","tag-planejamento","tag-planejamento-tributario","tag-simples-nacional","tag-tributacao"],"_links":{"self":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/comments?post=3459"}],"version-history":[{"count":2,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3459\/revisions"}],"predecessor-version":[{"id":3462,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/3459\/revisions\/3462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media\/3460"}],"wp:attachment":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media?parent=3459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/categories?post=3459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/tags?post=3459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}