{"id":4621,"date":"2024-09-18T15:08:42","date_gmt":"2024-09-18T18:08:42","guid":{"rendered":"https:\/\/www.fpnadvogados.com.br\/site\/?p=4621"},"modified":"2024-12-09T17:06:05","modified_gmt":"2024-12-09T20:06:05","slug":"semana-ods-na-pratica-destaca-papel-das-mulheres-em-acoes-esg","status":"publish","type":"post","link":"https:\/\/www.fpnadvogados.com.br\/site\/semana-ods-na-pratica-destaca-papel-das-mulheres-em-acoes-esg\/","title":{"rendered":"Semana ODS na Pr\u00e1tica destaca papel das mulheres em a\u00e7\u00f5es ESG"},"content":{"rendered":"<div>De 23 a 27 de setembro, v\u00e1rias cidades do pa\u00eds estar\u00e3o envolvidas na Semana ODS na Pr\u00e1tica, um movimento que busca disseminar conhecimento sobre os Objetivos de Desenvolvimento Sustent\u00e1vel, defendidos pela Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU). Em Blumenau, o semin\u00e1rio Mulheres em ESG, iniciativa do Instituto Brasileiro de ESG, \u00e9 um dos destaques da programa\u00e7\u00e3o e trar\u00e1 a contribui\u00e7\u00e3o de mulheres que atuam com essa tem\u00e1tica nas mais diferentes profiss\u00f5es.<\/div>\n<div>\u00a0<\/div>\n<div>A agenda gratuita ocorre no dia 24 de setembro, das 9h \u00e0s 17h30min, no audit\u00f3rio da Funda\u00e7\u00e3o Hermann Hering, no bairro Bom Retiro. A programa\u00e7\u00e3o prev\u00ea diversas atividades, entre elas, pain\u00e9is, palestras e medita\u00e7\u00e3o. Uma das presen\u00e7as confirmadas \u00e9 Sharon Haskel Koepsel, coordenadora de Governan\u00e7a Sustent\u00e1vel do escrit\u00f3rio Fl\u00e1vio Pinheiro Neto Advogados. Seu painel com o t\u00edtulo Criando uma Marca Forte: O Papel do ESG na Preven\u00e7\u00e3o de Riscos Reputacionais trar\u00e1 sua expertise em estrat\u00e9gias para construir uma marca resiliente, com exemplos de empresas que se fortalecem por meio de iniciativas sustent\u00e1veis.<\/div>\n<div>\u00a0<\/div>\n<div>\u201cEsse ser\u00e1 um espa\u00e7o importante para mostrarmos com exemplos pr\u00e1ticos como a\u00e7\u00f5es de responsabilidade ambiental, social e de governan\u00e7a s\u00e3o determinantes para a consolida\u00e7\u00e3o de uma imagem positiva da empresa, refletindo no seu posicionamento no mercado. E, claro, traremos insights sobre como integrar esses princ\u00edpios na estrat\u00e9gia de neg\u00f3cios\u201d, comenta Sharon. Ela ter\u00e1 como convidadas do painel Camile Bruns, consultoras de sustentabilidade, e Michele Mary Posso, advogada, que contribuir\u00e3o a partir de suas experi\u00eancias com a\u00e7\u00f5es ESG nos seus ramos de atua\u00e7\u00e3o.<\/div>\n<div>\u00a0<\/div>\n<div>Quem tamb\u00e9m marca presen\u00e7a como convidada, dessa vez do painel principal, \u00e9 Luciana Dobuchak, diretora comercial da IPEL, ind\u00fastria de papel do ramo tissue, considerada uma das maiores do segmento no pa\u00eds. Ela participa do debate sobre lideran\u00e7as engajadas e protagonistas em ESG, com o tema Como incorporar a agenda ESG na estrat\u00e9gia da organiza\u00e7\u00e3o, criando e compartilhando valor com os stakeholders, trazendo o exemplo de como essa quest\u00e3o tem sido conduzida na empresa.<\/div>\n<div>\u00a0<\/div>\n<div>\u201cNa IPEL, entendemos que a ado\u00e7\u00e3o das pr\u00e1ticas ESG vai muito al\u00e9m de cumprir exig\u00eancias ou seguir tend\u00eancias de mercado. Incorporamos essa agenda como parte essencial da nossa estrat\u00e9gia de neg\u00f3cio, buscando criar valor real para todos os nossos stakeholders. Isso envolve desde o uso eficiente de recursos naturais e o cuidado com o meio ambiente, at\u00e9 o investimento no bem-estar dos nossos colaboradores e a constru\u00e7\u00e3o de rela\u00e7\u00f5es transparentes e \u00e9ticas com nossos parceiros&#8221;, afirma Luciana.<\/div>\n<div>\u00a0<\/div>\n<div>Ap\u00f3s o evento, as participantes v\u00e3o se reunir para o Happy Hour ESG Night, onde dever\u00e3o intensificar a troca de experi\u00eancias e networking. A participa\u00e7\u00e3o \u00e9 gratuita, mediante inscri\u00e7\u00e3o, pois as vagas s\u00e3o limitadas. Mais informa\u00e7\u00f5es no link https:\/\/www.sympla.com.br\/evento\/esg-night-encerramento-seminario-mulheres-em-esg\/2636295.<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div><strong>Servi\u00e7o<\/strong><\/div>\n<div>\u00a0<\/div>\n<div>O qu\u00ea: Semin\u00e1rio Mulheres em ESG<\/div>\n<div>Quando: 24 de setembro<\/div>\n<div>Local: Funda\u00e7\u00e3o Hermann Hering (rua Hermann Hering, 1740, bairro Bom Retiro)<\/div>\n<div>Hor\u00e1rio: das 9h \u00e0s 17h30 \u2013 Happy Hour ESG Night a partir das 18h30; inscri\u00e7\u00f5es em https:\/\/www.sympla.com.br\/evento\/esg-night-encerramento-seminario-mulheres-em-esg\/2636295<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 23 a 27 de setembro, v\u00e1rias cidades do pa\u00eds estar\u00e3o envolvidas na Semana ODS na Pr\u00e1tica, um movimento que busca disseminar conhecimento sobre os Objetivos de Desenvolvimento Sustent\u00e1vel, defendidos pela Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU). Em Blumenau, o semin\u00e1rio Mulheres em ESG, iniciativa do Instituto Brasileiro de ESG, \u00e9 um dos destaques da programa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[40,191,190,93,95,189],"class_list":["post-4621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-blumenau","tag-eventos","tag-ods","tag-relp","tag-renegociacao","tag-seminario"],"_links":{"self":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/4621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/comments?post=4621"}],"version-history":[{"count":4,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/4621\/revisions"}],"predecessor-version":[{"id":4630,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/4621\/revisions\/4630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media\/4641"}],"wp:attachment":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media?parent=4621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/categories?post=4621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/tags?post=4621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}