{"id":4703,"date":"2025-02-04T13:15:40","date_gmt":"2025-02-04T16:15:40","guid":{"rendered":"https:\/\/www.fpnadvogados.com.br\/site\/?p=4703"},"modified":"2025-02-04T13:15:40","modified_gmt":"2025-02-04T16:15:40","slug":"decisao-do-stj-veda-que-socio-que-tenha-interesse-proprio-no-assunto-vote-na-assembleia-e-evita-conflito-de-interesses","status":"publish","type":"post","link":"https:\/\/www.fpnadvogados.com.br\/site\/decisao-do-stj-veda-que-socio-que-tenha-interesse-proprio-no-assunto-vote-na-assembleia-e-evita-conflito-de-interesses\/","title":{"rendered":"Decis\u00e3o do STJ veda que s\u00f3cio que tenha interesse pr\u00f3prio no assunto vote na assembleia e evita conflito de interesses"},"content":{"rendered":"\n<p>Em decis\u00e3o recente no Agravo em Recurso Especial n\u00ba 2462266 &#8211; do Rio de Janeiro, o Superior Tribunal de Justi\u00e7a (STJ) garantiu que \u00e9 poss\u00edvel a empresa afastar o s\u00f3cio administrador da gest\u00e3o, como tamb\u00e9m, excluir o s\u00f3cio minorit\u00e1rio em vota\u00e7\u00e3o de assembleia que tenha como ordem do dia tema que lhe seja de interesse direto. A decis\u00e3o abre jurisprud\u00eancia para casos an\u00e1logos e d\u00e1 um importante passo no que diz respeito a situa\u00e7\u00f5es em que interesses conflituosos podem colocar em risco a sa\u00fade financeira de um neg\u00f3cio.<\/p>\n\n\n\n<p>Com a decis\u00e3o do STJ, \u00e9 poss\u00edvel a destitui\u00e7\u00e3o do cargo de s\u00f3cio administrador pelos demais s\u00f3cios, pois, o art. 1.074, \u00a7 2\u00ba, do CC\/2002 impede que o s\u00f3cio que est\u00e1 sendo destitu\u00eddo vote na delibera\u00e7\u00e3o a respeito de sua pr\u00f3pria destitui\u00e7\u00e3o do cargo, eis que o assunto conflita diretamente com seus interesses financeiros e pessoais. Passa a valer, nesta situa\u00e7\u00e3o, somente o voto dos demais s\u00f3cios e a participa\u00e7\u00e3o societ\u00e1ria do s\u00f3cio administrador deixa de ser computada na assembleia. O principal fator que levou \u00e0 decis\u00e3o \u00e9 a necessidade de se garantir, acima de tudo, os interesses da empresa e sua estabilidade financeira, evitando que interesses pessoais se sobreponham a eles.<\/p>\n\n\n\n<p>Em regra, o direito de um s\u00f3cio participar de assembleias empresariais \u00e9 proporcional \u00e0 sua quota no capital social, mas \u00e9 fundamental observar que o conflito de interesses pode ser uma situa\u00e7\u00e3o n\u00e3o rara, especialmente no que diz respeito ao s\u00f3cio administrador. Preservar os interesses do neg\u00f3cio acima de uma figura da sociedade \u00e9 fundamental para que as decis\u00f5es sejam baseadas em preceitos \u00e9ticos e alinhados com as necessidades da empresa em si, apoiando seu crescimento.<\/p>\n\n\n\n<p>Assim, esta decis\u00e3o do STJ abre precedentes para que outras situa\u00e7\u00f5es que est\u00e3o sendo discutidas no \u00e2mbito societ\u00e1rio sejam analisadas sob o vi\u00e9s de eventual conflito de interesse de algum s\u00f3cio no tema que se ir\u00e1 deliberar, para que sua participa\u00e7\u00e3o societ\u00e1ria n\u00e3o seja contabilizada quando da vota\u00e7\u00e3o, priorizando os interesses da empresa e do neg\u00f3cio.<\/p>\n\n\n\n<p>Na mesma esteira caminha esta interpreta\u00e7\u00e3o quando se fala de exclus\u00e3o de s\u00f3cios minorit\u00e1rios, prevista pelo artigo 1.085 do C\u00f3digo Civil. Entre as exig\u00eancias a serem observadas para que tal exclus\u00e3o do quadro societ\u00e1rio ocorra, est\u00e1 o fato de que a iniciativa tenha previs\u00e3o expressa em contrato social, al\u00e9m disso, e, da mesma forma, a assembleia permita que o s\u00f3cio que est\u00e1 sendo exclu\u00eddo possa apresentar sua defesa antes da vota\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para a empresa, decis\u00f5es como esta s\u00e3o favor\u00e1veis e fortalecem o dever de lealdade dos s\u00f3cios, priorizando os interesses da sociedade. No entanto, vale refor\u00e7ar que para melhor gest\u00e3o de todos os temas societ\u00e1rios pelos s\u00f3cios \u00e9 recomend\u00e1vel a formaliza\u00e7\u00e3o de um acordo de s\u00f3cios, contendo todos os ajustes societ\u00e1rios, evitando conflitos e interpreta\u00e7\u00f5es diferentes de combinados existentes. Contratos empresariais bem estruturados garantem a previsibilidade das solu\u00e7\u00f5es de impasses, evitando a judicializa\u00e7\u00e3o e proporcionam agilidade para a tomada de decis\u00f5es.<\/p>\n\n\n\n<p><strong>Sobre o escrit\u00f3rio Fl\u00e1vio Pinheiro Neto Advogados<br><\/strong><br>Formado por uma equipe altamente qualificada, o escrit\u00f3rio Fl\u00e1vio Pinheiro Neto Advogados destaca-se pela ampla compet\u00eancia t\u00e9cnica e pelo atendimento que valoriza a proximidade com os clientes. Os juristas t\u00eam como miss\u00e3o traduzir o ambiente legal para o dia a dia das empresas, garantindo o melhor cen\u00e1rio a cada neg\u00f3cio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em decis\u00e3o recente no Agravo em Recurso Especial n\u00ba 2462266 &#8211; do Rio de Janeiro, o Superior Tribunal de Justi\u00e7a (STJ) garantiu que \u00e9 poss\u00edvel a empresa afastar o s\u00f3cio administrador da gest\u00e3o, como tamb\u00e9m, excluir o s\u00f3cio minorit\u00e1rio em vota\u00e7\u00e3o de assembleia que tenha como ordem do dia tema que lhe seja de interesse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/4703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/comments?post=4703"}],"version-history":[{"count":1,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/4703\/revisions"}],"predecessor-version":[{"id":4705,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/posts\/4703\/revisions\/4705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media\/4704"}],"wp:attachment":[{"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/media?parent=4703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/categories?post=4703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpnadvogados.com.br\/site\/wp-json\/wp\/v2\/tags?post=4703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}